{"id":351,"date":"2024-03-21T17:14:41","date_gmt":"2024-03-21T16:14:41","guid":{"rendered":"https:\/\/dev.asleman.org\/?page_id=351"},"modified":"2025-11-18T12:59:14","modified_gmt":"2025-11-18T11:59:14","slug":"actualites","status":"publish","type":"page","link":"https:\/\/asleman.org\/en\/actualites\/","title":{"rendered":"News"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"351\" class=\"elementor elementor-351\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3727df0 e-flex e-con-boxed e-con e-parent\" data-id=\"3727df0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe95a55 elementor-widget elementor-widget-heading\" data-id=\"fe95a55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">News from the ASL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17e14a0 e-flex e-con-boxed e-con e-parent\" data-id=\"17e14a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9238277 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"9238277\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-23161 post type-post status-publish format-standard has-post-thumbnail hentry category-espace-leman tag-leman tag-lessive tag-phosphate tag-pollution tag-societe-civile\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/08\/04\/nouvelle-exposition-jusquau-16-octobre-a-lespace-leman-leman-etre-vivant\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/HYDROMONDES_EXPO_INSTA-1-copie.jpg\" class=\"attachment-full size-full wp-image-23079\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/HYDROMONDES_EXPO_INSTA-1-copie.jpg 1080w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/HYDROMONDES_EXPO_INSTA-1-copie-240x300.jpg 240w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/HYDROMONDES_EXPO_INSTA-1-copie-819x1024.jpg 819w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/HYDROMONDES_EXPO_INSTA-1-copie-768x960.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/HYDROMONDES_EXPO_INSTA-1-copie-10x12.jpg 10w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Espace L\u00e9man<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/08\/04\/nouvelle-exposition-jusquau-16-octobre-a-lespace-leman-leman-etre-vivant\/\" >\n\t\t\t\tNew exhibition until 16 October at the Espace L\u00e9man: L\u00c9MAN \u00caTRE VIVANT\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/08\/04\/nouvelle-exposition-jusquau-16-octobre-a-lespace-leman-leman-etre-vivant\/\" aria-label=\"Read more about Nouvelle exposition jusqu&#8217;au 16 octobre \u00e0 l&#8217;Espace L\u00e9man : L\u00c9MAN \u00caTRE VIVANT\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 August 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22914 post type-post status-publish format-standard has-post-thumbnail hentry category-asl tag-leman tag-lessive tag-phosphate tag-pollution tag-societe-civile\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/07\/01\/il-y-a-40-ans-la-suisse-interdisait-les-phosphates-dans-les-lessives-une-victoire-citoyenne-pour-le-leman\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"818\" height=\"615\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Bains-interdits.jpg\" class=\"attachment-full size-full wp-image-22921\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Bains-interdits.jpg 818w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Bains-interdits-300x226.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Bains-interdits-768x577.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Bains-interdits-16x12.jpg 16w\" sizes=\"(max-width: 818px) 100vw, 818px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">ASL<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/07\/01\/il-y-a-40-ans-la-suisse-interdisait-les-phosphates-dans-les-lessives-une-victoire-citoyenne-pour-le-leman\/\" >\n\t\t\t\t40 years ago, Switzerland banned phosphates in laundry detergents: a citizen victory for Lake Geneva\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/07\/01\/il-y-a-40-ans-la-suisse-interdisait-les-phosphates-dans-les-lessives-une-victoire-citoyenne-pour-le-leman\/\" aria-label=\"Read more about Il y a 40 ans, la Suisse interdisait les phosphates dans les  lessives : une victoire citoyenne pour le L\u00e9man\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 July 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22925 post type-post status-publish format-standard has-post-thumbnail hentry category-lemaniques\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/06\/24\/lemaniques-no-139-lemanscope-un-defi-reussi-pour-democratiser-la-science\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"905\" height=\"1282\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Lem139.jpg\" class=\"attachment-full size-full wp-image-22923\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Lem139.jpg 905w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Lem139-212x300.jpg 212w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Lem139-723x1024.jpg 723w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Lem139-768x1088.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Lem139-8x12.jpg 8w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Lake Geneva region<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/06\/24\/lemaniques-no-139-lemanscope-un-defi-reussi-pour-democratiser-la-science\/\" >\n\t\t\t\tL\u00e9maniques no. 139 \u2013 L\u00e9manscope, a successful challenge in making science accessible to all\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/06\/24\/lemaniques-no-139-lemanscope-un-defi-reussi-pour-democratiser-la-science\/\" aria-label=\"Read more about L\u00e9maniques no. 139 &#8211; L\u00e9manscope, un d\u00e9fi r\u00e9ussi pour d\u00e9mocratiser la science\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t24 June 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22746 post type-post status-publish format-standard has-post-thumbnail hentry category-evenements\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/05\/05\/46e-assemblee-generale-inscription-programme-et-acces-lundi-11-juin-2025-a-versoix-geneve\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1767\" height=\"996\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/05\/46AG.png\" class=\"attachment-full size-full wp-image-22747\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/05\/46AG.png 1767w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/05\/46AG-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/05\/46AG-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/05\/46AG-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/05\/46AG-1536x866.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/05\/46AG-18x10.png 18w\" sizes=\"(max-width: 1767px) 100vw, 1767px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Events<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/05\/05\/46e-assemblee-generale-inscription-programme-et-acces-lundi-11-juin-2025-a-versoix-geneve\/\" >\n\t\t\t\t46th General Assembly: registration, agenda and access - Thursday 11 June 2026 in Versoix (Geneva)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/05\/05\/46e-assemblee-generale-inscription-programme-et-acces-lundi-11-juin-2025-a-versoix-geneve\/\" aria-label=\"Read more about 46\u00e8me assembl\u00e9e g\u00e9n\u00e9rale : inscription, programme et acc\u00e8s &#8211; jeudi 11 juin 2026 \u00e0 Versoix(Gen\u00e8ve)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 May 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22532 post type-post status-publish format-standard has-post-thumbnail hentry category-webinaire\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/03\/12\/conference-en-ligne-leman-leveil-dun-peuple-rediffusion-disponible\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/03\/Rediffusion-conference-du-9-mars-2026-Leman-leveil-dun-peuple.png\" class=\"attachment-full size-full wp-image-22533\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/03\/Rediffusion-conference-du-9-mars-2026-Leman-leveil-dun-peuple.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/03\/Rediffusion-conference-du-9-mars-2026-Leman-leveil-dun-peuple-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/03\/Rediffusion-conference-du-9-mars-2026-Leman-leveil-dun-peuple-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/03\/Rediffusion-conference-du-9-mars-2026-Leman-leveil-dun-peuple-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/03\/Rediffusion-conference-du-9-mars-2026-Leman-leveil-dun-peuple-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/03\/Rediffusion-conference-du-9-mars-2026-Leman-leveil-dun-peuple-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Webinar<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/03\/12\/conference-en-ligne-leman-leveil-dun-peuple-rediffusion-disponible\/\" >\n\t\t\t\tOnline conference: L\u00e9man, l'\u00e9veil d'un peuple (replay available)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/03\/12\/conference-en-ligne-leman-leveil-dun-peuple-rediffusion-disponible\/\" aria-label=\"Read more about Online conference: L\u00e9man, l&#039;\u00e9veil d&#039;un peuple (replay available)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t12 March 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22398 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/nouveau-suivez-nos-evenements-grace-a-notre-agenda-en-ligne\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-scaled.jpg\" class=\"attachment-full size-full wp-image-22401\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-300x225.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-1024x768.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-768x576.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-1536x1152.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-2048x1536.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/agenda-de-lASL-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/nouveau-suivez-nos-evenements-grace-a-notre-agenda-en-ligne\/\" >\n\t\t\t\tNew: follow our events in our online diary\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/nouveau-suivez-nos-evenements-grace-a-notre-agenda-en-ligne\/\" aria-label=\"Read more about New: follow our events in our online diary\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26 February 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22392 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/soutenez-nos-camps-grace-a-vos-achats-a-la-migros\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/support-my-camp-migros.png\" class=\"attachment-full size-full wp-image-22395\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/support-my-camp-migros.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/support-my-camp-migros-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/support-my-camp-migros-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/support-my-camp-migros-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/support-my-camp-migros-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/support-my-camp-migros-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/soutenez-nos-camps-grace-a-vos-achats-a-la-migros\/\" >\n\t\t\t\tSupport our camps with your Migros purchases!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/soutenez-nos-camps-grace-a-vos-achats-a-la-migros\/\" aria-label=\"Read more about Support our camps with your Migros purchases!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26 February 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22389 post type-post status-publish format-standard has-post-thumbnail hentry category-politique\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/lasl-soutient-lappel-en-faveur-de-leau-potable\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1365\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/Trinkwasser-Appell-Header-Desktop-ce90da83e2e6.webp\" class=\"attachment-full size-full wp-image-22390\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/Trinkwasser-Appell-Header-Desktop-ce90da83e2e6.webp 1920w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/Trinkwasser-Appell-Header-Desktop-ce90da83e2e6-300x213.webp 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/Trinkwasser-Appell-Header-Desktop-ce90da83e2e6-1024x728.webp 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/Trinkwasser-Appell-Header-Desktop-ce90da83e2e6-768x546.webp 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/Trinkwasser-Appell-Header-Desktop-ce90da83e2e6-1536x1092.webp 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/02\/Trinkwasser-Appell-Header-Desktop-ce90da83e2e6-18x12.webp 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Policy<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/lasl-soutient-lappel-en-faveur-de-leau-potable\/\" >\n\t\t\t\tThe ASL supports the appeal in favour of drinking water\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/02\/26\/lasl-soutient-lappel-en-faveur-de-leau-potable\/\" aria-label=\"Read more about The ASL supports the appeal for drinking water\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26 February 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22250 post type-post status-publish format-standard has-post-thumbnail hentry category-asl\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/nos-offres-de-stage-et-service-civil-travaillez-au-coeur-du-leman-avec-lasl\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1442\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-scaled.jpg\" class=\"attachment-full size-full wp-image-22247\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-300x169.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-1024x577.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-768x433.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-1536x865.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-2048x1154.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Photo-dequipe-Selection_P1055253-18x10.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">ASL<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/nos-offres-de-stage-et-service-civil-travaillez-au-coeur-du-leman-avec-lasl\/\" >\n\t\t\t\tOur internship and civil service offers, work in the heart of Lake Geneva with ASL\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/nos-offres-de-stage-et-service-civil-travaillez-au-coeur-du-leman-avec-lasl\/\" aria-label=\"Read more about Our internship and civil service offers, work in the heart of Lake Geneva with ASL\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t22 January 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22243 post type-post status-publish format-standard has-post-thumbnail hentry category-flore\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/mise-a-jour-de-la-cartographie-des-herbiers-du-littoral-lemanique-genevois\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-scaled.jpg\" class=\"attachment-full size-full wp-image-22246\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-300x225.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-1024x768.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-768x576.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-1536x1152.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-2048x1536.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/P.-Mulattieri-Chara-Aspera-Pointe-a-la-Bise-BiolEau-Sarl-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Flore<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/mise-a-jour-de-la-cartographie-des-herbiers-du-littoral-lemanique-genevois\/\" >\n\t\t\t\tUpdating the mapping of meadows along the Geneva Lake shoreline\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/mise-a-jour-de-la-cartographie-des-herbiers-du-littoral-lemanique-genevois\/\" aria-label=\"Read more about Updated mapping of seagrass beds along Geneva&#039;s Lake Geneva coastline\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t22 January 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22260 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/lasl-soutient-la-petition-liberer-et-proteger-le-glacier-du-rhone\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Glacier-Rhone-Patrick-Robert-Doyle-k4cFCXR7bG0-unsplash.jpg\" class=\"attachment-full size-full wp-image-22263\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Glacier-Rhone-Patrick-Robert-Doyle-k4cFCXR7bG0-unsplash.jpg 1920w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Glacier-Rhone-Patrick-Robert-Doyle-k4cFCXR7bG0-unsplash-300x169.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Glacier-Rhone-Patrick-Robert-Doyle-k4cFCXR7bG0-unsplash-1024x576.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Glacier-Rhone-Patrick-Robert-Doyle-k4cFCXR7bG0-unsplash-768x432.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Glacier-Rhone-Patrick-Robert-Doyle-k4cFCXR7bG0-unsplash-1536x864.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/01\/Glacier-Rhone-Patrick-Robert-Doyle-k4cFCXR7bG0-unsplash-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/lasl-soutient-la-petition-liberer-et-proteger-le-glacier-du-rhone\/\" >\n\t\t\t\tThe ASL supports the \u00abLib\u00e9rer et prot\u00e9ger le glacier du Rh\u00f4ne\u00bb petition\u00bb\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2026\/01\/22\/lasl-soutient-la-petition-liberer-et-proteger-le-glacier-du-rhone\/\" aria-label=\"Read more about The ASL supports the \u00abLib\u00e9rer et prot\u00e9ger le glacier du Rh\u00f4ne\u00bb petition\u00bb\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t22 January 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21903 post type-post status-publish format-standard has-post-thumbnail hentry category-lemaniques\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/12\/15\/lemaniques-no-137-quand-le-leman-prend-des-airs-docean\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1811\" height=\"2560\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-scaled.jpg\" class=\"attachment-full size-full wp-image-21900\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-scaled.jpg 1811w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-212x300.jpg 212w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-724x1024.jpg 724w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-768x1086.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-1086x1536.jpg 1086w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-1448x2048.jpg 1448w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Lemaniques137_12_2025_WEB2_premiere-page-8x12.jpg 8w\" sizes=\"(max-width: 1811px) 100vw, 1811px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Lake Geneva region<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/12\/15\/lemaniques-no-137-quand-le-leman-prend-des-airs-docean\/\" >\n\t\t\t\tL\u00e9maniques no. 137 - When Lake Geneva takes on an oceanic air\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/12\/15\/lemaniques-no-137-quand-le-leman-prend-des-airs-docean\/\" aria-label=\"Read more about L\u00e9maniques no. 137 - When Lake Geneva takes on an oceanic air\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t15 December 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21906 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/12\/15\/les-recettes-du-leman-silure-au-curry-pour-les-fetes\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/recette-silure-curry.png\" class=\"attachment-full size-full wp-image-21909\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/recette-silure-curry.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/recette-silure-curry-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/recette-silure-curry-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/recette-silure-curry-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/recette-silure-curry-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/recette-silure-curry-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/12\/15\/les-recettes-du-leman-silure-au-curry-pour-les-fetes\/\" >\n\t\t\t\tLake Geneva recipes: Curried catfish for the festive season!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/12\/15\/les-recettes-du-leman-silure-au-curry-pour-les-fetes\/\" aria-label=\"Read more about Recipes from Lake Geneva: Curried catfish for the festive season!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t15 December 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21828 post type-post status-publish format-standard has-post-thumbnail hentry category-webinaire\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/12\/01\/conference-en-ligne-plastiques-dans-le-leman-overdose-lundi-15-decembre-de-19h-a-20h\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Webinaire-15-decembre-2025-Plastiques-dans-le-Leman-overdose-.png\" class=\"attachment-full size-full wp-image-21829\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Webinaire-15-decembre-2025-Plastiques-dans-le-Leman-overdose-.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Webinaire-15-decembre-2025-Plastiques-dans-le-Leman-overdose--300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Webinaire-15-decembre-2025-Plastiques-dans-le-Leman-overdose--1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Webinaire-15-decembre-2025-Plastiques-dans-le-Leman-overdose--768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Webinaire-15-decembre-2025-Plastiques-dans-le-Leman-overdose--1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/Webinaire-15-decembre-2025-Plastiques-dans-le-Leman-overdose--18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Webinar<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/12\/01\/conference-en-ligne-plastiques-dans-le-leman-overdose-lundi-15-decembre-de-19h-a-20h\/\" >\n\t\t\t\tOnline conference: Plastics in Lake Geneva, an overdose? - Monday 15 December from 7pm to 8pm (replay available)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/12\/01\/conference-en-ligne-plastiques-dans-le-leman-overdose-lundi-15-decembre-de-19h-a-20h\/\" aria-label=\"Read more about Online conference: Plastics in Lake Geneva, an overdose? - Monday 15 December from 7pm to 8pm (replay available)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 December 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21831 post type-post status-publish format-standard has-post-thumbnail hentry category-boutique\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/12\/01\/offrez-des-cadeaux-tout-en-soutenant-nos-actions-pour-le-leman-2\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/boutique-Camps-ETL-promo-cadeau-fin-annee.png\" class=\"attachment-full size-full wp-image-21832\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/boutique-Camps-ETL-promo-cadeau-fin-annee.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/boutique-Camps-ETL-promo-cadeau-fin-annee-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/boutique-Camps-ETL-promo-cadeau-fin-annee-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/boutique-Camps-ETL-promo-cadeau-fin-annee-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/boutique-Camps-ETL-promo-cadeau-fin-annee-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/12\/boutique-Camps-ETL-promo-cadeau-fin-annee-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Shop<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/12\/01\/offrez-des-cadeaux-tout-en-soutenant-nos-actions-pour-le-leman-2\/\" >\n\t\t\t\tGive gifts and support our actions for Lake Geneva\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/12\/01\/offrez-des-cadeaux-tout-en-soutenant-nos-actions-pour-le-leman-2\/\" aria-label=\"Read more about Give gifts and support our actions for Lake Geneva\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 December 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21541 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/11\/11\/cine-debat-retrouvez-lasl-au-festival-du-film-pour-la-terre-vendredi-28-novembre-a-20h\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/11\/Format-miniature-newslettersite-asl.png\" class=\"attachment-full size-full wp-image-21542\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/11\/Format-miniature-newslettersite-asl.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/11\/Format-miniature-newslettersite-asl-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/11\/Format-miniature-newslettersite-asl-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/11\/Format-miniature-newslettersite-asl-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/11\/Format-miniature-newslettersite-asl-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/11\/Format-miniature-newslettersite-asl-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/11\/11\/cine-debat-retrouvez-lasl-au-festival-du-film-pour-la-terre-vendredi-28-novembre-a-20h\/\" >\n\t\t\t\tFilm-debate: join the ASL at the Earth Film Festival - Friday 28 November at 8pm\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/11\/11\/cine-debat-retrouvez-lasl-au-festival-du-film-pour-la-terre-vendredi-28-novembre-a-20h\/\" aria-label=\"Read more about Film debate: join ASL at the Earth Film Festival - Friday 28 November at 8pm\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t11 November 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21493 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/expo-actuelle-activites-ludiques-pour-decouvrir-le-leman-en-famille\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/animation-famille-expo.png\" class=\"attachment-full size-full wp-image-21494\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/animation-famille-expo.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/animation-famille-expo-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/animation-famille-expo-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/animation-famille-expo-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/animation-famille-expo-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/animation-famille-expo-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/expo-actuelle-activites-ludiques-pour-decouvrir-le-leman-en-famille\/\" >\n\t\t\t\tCurrent exhibition: fun activities to discover Lake Geneva with your family\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/expo-actuelle-activites-ludiques-pour-decouvrir-le-leman-en-famille\/\" aria-label=\"Read more about Expo actuelle: fun activities to discover Lake Geneva with your family\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21482 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conferences-lhistoire-du-leman-admirable-bien-commun-jeudi-27-novembre-a-19h30-a-cully\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2076\" height=\"1456\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37.jpg\" class=\"attachment-full size-full wp-image-21483\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37.jpg 2076w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37-300x210.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37-1024x718.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37-768x539.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37-1536x1077.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37-2048x1436.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/ML_2023_L_0178_20250317_13463663_37-18x12.jpg 18w\" sizes=\"(max-width: 2076px) 100vw, 2076px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conferences-lhistoire-du-leman-admirable-bien-commun-jeudi-27-novembre-a-19h30-a-cully\/\" >\n\t\t\t\tLectures: the history of Lake Geneva, an admirable common good - Thursday 27 November at 7.30pm in Cully\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conferences-lhistoire-du-leman-admirable-bien-commun-jeudi-27-novembre-a-19h30-a-cully\/\" aria-label=\"Read more about Lectures: the history of Lake Geneva, an admirable common good - Thursday 27 November at 7.30pm in Cully\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21479 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conference-creation-de-netleman-avec-amanda-melis-jeudi-20-novembre-de-18h-a-19h30-a-lespace-leman-geneve\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-scaled.jpg\" class=\"attachment-full size-full wp-image-21480\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-300x200.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-1024x683.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-768x512.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-1536x1024.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-2048x1365.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/NetLeman-Photo_groupe_Eaux-Vives-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conference-creation-de-netleman-avec-amanda-melis-jeudi-20-novembre-de-18h-a-19h30-a-lespace-leman-geneve\/\" >\n\t\t\t\tConference: \u00abCreating Net'L\u00e9man\u00bb with Amanda Melis - Thursday 20 November from 6pm to 7.30pm at Espace L\u00e9man (Geneva)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conference-creation-de-netleman-avec-amanda-melis-jeudi-20-novembre-de-18h-a-19h30-a-lespace-leman-geneve\/\" aria-label=\"Read more about Conference: \u00abCreating Net&#039;L\u00e9man\u00bb with Amanda Melis - Thursday 20 November from 6pm to 7.30pm at Espace L\u00e9man (Geneva)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21499 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conference-sur-la-moule-quagga-2eme-edition-des-rencontres-de-la-faune-genevoise-samedi-8-novembre-de-12h-a-12h30-a-lhepia-geneve\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1150\" height=\"1610\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/petit-Event-du-8-nov-conf-quagga.jpg\" class=\"attachment-full size-full wp-image-21500\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/petit-Event-du-8-nov-conf-quagga.jpg 1150w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/petit-Event-du-8-nov-conf-quagga-214x300.jpg 214w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/petit-Event-du-8-nov-conf-quagga-731x1024.jpg 731w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/petit-Event-du-8-nov-conf-quagga-768x1075.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/petit-Event-du-8-nov-conf-quagga-1097x1536.jpg 1097w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/petit-Event-du-8-nov-conf-quagga-9x12.jpg 9w\" sizes=\"(max-width: 1150px) 100vw, 1150px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conference-sur-la-moule-quagga-2eme-edition-des-rencontres-de-la-faune-genevoise-samedi-8-novembre-de-12h-a-12h30-a-lhepia-geneve\/\" >\n\t\t\t\tConference on the Quagga mussel (2nd edition of the Geneva Wildlife Meetings) - Saturday 8 November from 12 noon to 12.30 pm at HEPIA (Geneva)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/conference-sur-la-moule-quagga-2eme-edition-des-rencontres-de-la-faune-genevoise-samedi-8-novembre-de-12h-a-12h30-a-lhepia-geneve\/\" aria-label=\"Read more about Conference on the Quagga mussel (2nd edition of the Geneva Wildlife Meetings) - Saturday 8 November from 12 noon to 12.30 pm at HEPIA (Geneva)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21496 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/projection-de-film-et-table-ronde-sur-la-moule-quagga-mardi-4-novembre-de-18h-a-20h-a-lunil-lausanne\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/2025.10.30-affiche-table-ronde-unil.jpeg\" class=\"attachment-full size-full wp-image-21497\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/2025.10.30-affiche-table-ronde-unil.jpeg 1200w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/2025.10.30-affiche-table-ronde-unil-300x225.jpeg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/2025.10.30-affiche-table-ronde-unil-1024x768.jpeg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/2025.10.30-affiche-table-ronde-unil-768x576.jpeg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/2025.10.30-affiche-table-ronde-unil-16x12.jpeg 16w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/projection-de-film-et-table-ronde-sur-la-moule-quagga-mardi-4-novembre-de-18h-a-20h-a-lunil-lausanne\/\" >\n\t\t\t\tFilm screening and round table discussion on the Quagga mussel - Tuesday 4 November from 6pm to 8pm at UNIL (Lausanne)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/projection-de-film-et-table-ronde-sur-la-moule-quagga-mardi-4-novembre-de-18h-a-20h-a-lunil-lausanne\/\" aria-label=\"Read more about Film screening and round table on the Quagga Mussel - Tuesday 4 November from 6pm to 8pm at UNIL (Lausanne)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21485 post type-post status-publish format-standard has-post-thumbnail hentry category-pollution tag-pollution tag-triazole\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/124-triazole-dans-les-eaux-du-leman-lasl-demande-des-eclaircissements\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Leman-et-mouettes-Yves-ykaiavu-Pixabay-5989714_1280.jpg\" class=\"attachment-full size-full wp-image-21486\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Leman-et-mouettes-Yves-ykaiavu-Pixabay-5989714_1280.jpg 1280w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Leman-et-mouettes-Yves-ykaiavu-Pixabay-5989714_1280-300x169.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Leman-et-mouettes-Yves-ykaiavu-Pixabay-5989714_1280-1024x576.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Leman-et-mouettes-Yves-ykaiavu-Pixabay-5989714_1280-768x432.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Leman-et-mouettes-Yves-ykaiavu-Pixabay-5989714_1280-18x10.jpg 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Pollution<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/124-triazole-dans-les-eaux-du-leman-lasl-demande-des-eclaircissements\/\" >\n\t\t\t\t1,2,4-triazole in the waters of Lake Geneva: the ASL asks for clarification\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/30\/124-triazole-dans-les-eaux-du-leman-lasl-demande-des-eclaircissements\/\" aria-label=\"Read more about 1,2,4-triazole in the waters of Lake Geneva: ASL calls for clarification\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21435 post type-post status-publish format-standard has-post-thumbnail hentry category-faune\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/16\/une-info-en-60-secondes-nouvel-article-sur-les-odonates\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/sympetrum-striolatum-web.jpg\" class=\"attachment-full size-full wp-image-21433\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/sympetrum-striolatum-web.jpg 800w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/sympetrum-striolatum-web-300x200.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/sympetrum-striolatum-web-768x512.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/sympetrum-striolatum-web-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Fauna<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/16\/une-info-en-60-secondes-nouvel-article-sur-les-odonates\/\" >\n\t\t\t\tNews in 60 seconds: a new article on Odonata!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/16\/une-info-en-60-secondes-nouvel-article-sur-les-odonates\/\" aria-label=\"Read more about 60 seconds of news: a new article on Odonata!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21414 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/conference-le-leman-une-agonie-surveillee-avec-eric-burnand-mardi-14-octobre-a-18h00\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/Eric-BURNAND.png\" class=\"attachment-full size-full wp-image-21241\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/Eric-BURNAND.png 1920w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/Eric-BURNAND-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/Eric-BURNAND-1024x576.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/Eric-BURNAND-768x432.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/Eric-BURNAND-1536x864.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/Eric-BURNAND-18x10.png 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/conference-le-leman-une-agonie-surveillee-avec-eric-burnand-mardi-14-octobre-a-18h00\/\" >\n\t\t\t\tLecture: Le L\u00e9man, une agonie surveill\u00e9e with \u00c9ric Burnand - Tuesday 14 October at 6.00 pm\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/conference-le-leman-une-agonie-surveillee-avec-eric-burnand-mardi-14-octobre-a-18h00\/\" aria-label=\"Read more about Conference: Le L\u00e9man, une agonie surveill\u00e9e with \u00c9ric Burnand - Tuesday 14 October at 6.00 pm\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21406 post type-post status-publish format-standard has-post-thumbnail hentry category-lemaniques\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/lemaniques-no-136-avenir-incertain-pour-les-poissons-phares-du-leman\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1311\" height=\"1865\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Lem136.jpg\" class=\"attachment-full size-full wp-image-21354\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Lem136.jpg 1311w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Lem136-211x300.jpg 211w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Lem136-720x1024.jpg 720w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Lem136-768x1093.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Lem136-1080x1536.jpg 1080w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Lem136-8x12.jpg 8w\" sizes=\"(max-width: 1311px) 100vw, 1311px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Lake Geneva region<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/lemaniques-no-136-avenir-incertain-pour-les-poissons-phares-du-leman\/\" >\n\t\t\t\tL\u00e9maniques no. 136 - An uncertain future for Lake Geneva's leading fish species\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/lemaniques-no-136-avenir-incertain-pour-les-poissons-phares-du-leman\/\" aria-label=\"Read more about L\u00e9maniques no. 136 - Uncertain future for Lake Geneva&#039;s leading fish species\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21410 post type-post status-publish format-standard has-post-thumbnail hentry category-expo\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/exposition-a-lespace-leman-les-enfants-deviennent-detectives-le-temps-dune-enquete\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-parcours-enfant.png\" class=\"attachment-full size-full wp-image-21412\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-parcours-enfant.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-parcours-enfant-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-parcours-enfant-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-parcours-enfant-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-parcours-enfant-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-parcours-enfant-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Expo<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/exposition-a-lespace-leman-les-enfants-deviennent-detectives-le-temps-dune-enquete\/\" >\n\t\t\t\tExhibition at Espace L\u00e9man: children become detectives for the duration of an investigation!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/exposition-a-lespace-leman-les-enfants-deviennent-detectives-le-temps-dune-enquete\/\" aria-label=\"Read more about Exhibition at Espace L\u00e9man: children become detectives during an investigation!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20835 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/animation-decouverte-du-monde-invisible-du-leman-les-21-et-23-octobre-passeports-vacances-morges-et-environs\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2048\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-scaled.jpg\" class=\"attachment-full size-full wp-image-20840\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-300x240.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-1024x819.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-768x614.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-1536x1229.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-2048x1638.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/passeport-vacances-20250814_101421-15x12.jpg 15w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/animation-decouverte-du-monde-invisible-du-leman-les-21-et-23-octobre-passeports-vacances-morges-et-environs\/\" >\n\t\t\t\tDiscover the invisible world of Lake Geneva\u201c events on 21 and 23 October (Morges and surrounding area holiday passports)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/animation-decouverte-du-monde-invisible-du-leman-les-21-et-23-octobre-passeports-vacances-morges-et-environs\/\" aria-label=\"Read more about \u201cDiscover the invisible world of Lake Geneva\u201d on 21 and 23 October (Morges and surrounding area holiday passports)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21420 post type-post status-publish format-standard has-post-thumbnail hentry category-asl\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/le-leman-et-lasl-ont-besoin-de-vous-soutenez-nos-actions\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-soutenez-nous.png\" class=\"attachment-full size-full wp-image-21421\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-soutenez-nous.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-soutenez-nous-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-soutenez-nous-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-soutenez-nous-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-soutenez-nous-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/10\/Miniature-news-site-ASL-soutenez-nous-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">ASL<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/le-leman-et-lasl-ont-besoin-de-vous-soutenez-nos-actions\/\" >\n\t\t\t\tLe L\u00e9man and ASL need you: support our actions\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/le-leman-et-lasl-ont-besoin-de-vous-soutenez-nos-actions\/\" aria-label=\"Read more about Le L\u00e9man and ASL need you: support our actions\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21417 post type-post status-publish format-standard has-post-thumbnail hentry category-renouees\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/appel-a-benevoles-inscrivez-vous-pour-les-derniers-arrachages-de-la-saison\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-scaled.jpg\" class=\"attachment-full size-full wp-image-20847\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-300x225.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-1024x768.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-768x576.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-1536x1152.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-2048x1536.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Knotweed<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/appel-a-benevoles-inscrivez-vous-pour-les-derniers-arrachages-de-la-saison\/\" >\n\t\t\t\tCall for volunteers: sign up for the last grubbings of the season!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/10\/08\/appel-a-benevoles-inscrivez-vous-pour-les-derniers-arrachages-de-la-saison\/\" aria-label=\"Read more about Call for volunteers: sign up for the last grubbings of the season!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 October 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-21229 post type-post status-publish format-standard has-post-thumbnail hentry category-expo\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/09\/16\/nouvelle-exposition-a-lespace-leman-de-lasl-des-aujourdhui\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"460\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/2025.08.07-Minature-news-site-internet-ASL-asl_visuel_expo_2025_820x460.jpg\" class=\"attachment-full size-full wp-image-21231\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/2025.08.07-Minature-news-site-internet-ASL-asl_visuel_expo_2025_820x460.jpg 820w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/2025.08.07-Minature-news-site-internet-ASL-asl_visuel_expo_2025_820x460-300x168.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/2025.08.07-Minature-news-site-internet-ASL-asl_visuel_expo_2025_820x460-768x431.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/09\/2025.08.07-Minature-news-site-internet-ASL-asl_visuel_expo_2025_820x460-18x10.jpg 18w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Expo<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/09\/16\/nouvelle-exposition-a-lespace-leman-de-lasl-des-aujourdhui\/\" >\n\t\t\t\tNew exhibition at the ASL's Espace L\u00e9man from today!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/09\/16\/nouvelle-exposition-a-lespace-leman-de-lasl-des-aujourdhui\/\" aria-label=\"Read more about New exhibition at ASL&#039;s Espace L\u00e9man from today!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t16 September 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20842 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/lasl-partenaire-caritatif-du-triathlon-devian-3eme-edition-les-20-et-21-septembre\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-scaled.jpg\" class=\"attachment-full size-full wp-image-20843\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-300x200.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-1024x683.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-768x512.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-1536x1024.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-2048x1365.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Anais-David-Tri-Evian-samedi-326-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/lasl-partenaire-caritatif-du-triathlon-devian-3eme-edition-les-20-et-21-septembre\/\" >\n\t\t\t\tASL, Charity Partner of the \u00c9vian Triathlon 3rd edition on 20 and 21 September\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/lasl-partenaire-caritatif-du-triathlon-devian-3eme-edition-les-20-et-21-septembre\/\" aria-label=\"Read more about ASL, Charity Partner of the \u00c9vian Triathlon 3rd edition on 20 and 21 September\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20849 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/conferences-les-plastiques-dans-le-leman-et-les-bonnes-pratiques-les-4-et-24-septembre-a-evian\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-scaled.jpg\" class=\"attachment-full size-full wp-image-20851\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-300x200.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-1024x683.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-768x512.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-1536x1025.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-2048x1366.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Adrien-Bonny-ASL-Plastic-JFP-9008-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/conferences-les-plastiques-dans-le-leman-et-les-bonnes-pratiques-les-4-et-24-septembre-a-evian\/\" >\n\t\t\t\tConferences: plastics in Lake Geneva and best practices, 4 and 24 September in Evian\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/conferences-les-plastiques-dans-le-leman-et-les-bonnes-pratiques-les-4-et-24-septembre-a-evian\/\" aria-label=\"Read more about Conferences: plastics in Lake Geneva and best practice, 4 and 24 September in Evian\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20846 post type-post status-publish format-standard has-post-thumbnail hentry category-renouees\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/appel-a-benevoles-participez-a-nos-actions-darrachage-en-septembre\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-scaled.jpg\" class=\"attachment-full size-full wp-image-20847\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-300x225.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-1024x768.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-768x576.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-1536x1152.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-2048x1536.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/20250514_VD_Bussigny_benevole1-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Knotweed<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/appel-a-benevoles-participez-a-nos-actions-darrachage-en-septembre\/\" >\n\t\t\t\tCall for volunteers: take part in our grubbing-up operations in September!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/appel-a-benevoles-participez-a-nos-actions-darrachage-en-septembre\/\" aria-label=\"Read more about Call for volunteers: take part in our grubbing-up operations in September!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20853 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/journee-suisse-des-poissons-stand-asl-a-la-maison-de-la-peche-ge-30-aout-de-9h30-a-16h\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1442\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-scaled.jpg\" class=\"attachment-full size-full wp-image-20855\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-300x169.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-1024x577.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-768x433.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-1536x865.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-2048x1154.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/08\/Journee-poissons-monde-invisible-RS_P1022777-18x10.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/journee-suisse-des-poissons-stand-asl-a-la-maison-de-la-peche-ge-30-aout-de-9h30-a-16h\/\" >\n\t\t\t\tSwiss Fish Day: ASL stand at the Maison de la P\u00eache (GE), 30 August from 9.30am to 4pm\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/journee-suisse-des-poissons-stand-asl-a-la-maison-de-la-peche-ge-30-aout-de-9h30-a-16h\/\" aria-label=\"Read more about Swiss Fish Day: ASL stand at the Maison de la P\u00eache (GE), 30 August from 9.30am to 4pm\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20829 post type-post status-publish format-standard has-post-thumbnail hentry category-faune\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/plongez-dans-lunivers-meconnu-des-mollusques-du-leman\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-scaled.jpg\" class=\"attachment-full size-full wp-image-20402\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-300x200.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-1024x683.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-768x512.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-1536x1024.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-2048x1365.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Quagga_Leman_Marc-Bernard_ASL-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Fauna<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/plongez-dans-lunivers-meconnu-des-mollusques-du-leman\/\" >\n\t\t\t\tDive into the little-known world of Lake Geneva molluscs!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/08\/27\/plongez-dans-lunivers-meconnu-des-mollusques-du-leman\/\" aria-label=\"Read more about Dive into the little-known world of Lake Geneva molluscs!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20673 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/08\/05\/eveil-du-leman-ne-manquez-pas-les-deux-dernieres-sorties-de-la-saison-11-et-14-aout\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-scaled.jpg\" class=\"attachment-full size-full wp-image-20674\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-300x225.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-1024x768.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-768x576.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-1536x1152.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-2048x1536.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Eveil-du-Leman-artistique-20240816_093035-16x12.jpg 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/08\/05\/eveil-du-leman-ne-manquez-pas-les-deux-dernieres-sorties-de-la-saison-11-et-14-aout\/\" >\n\t\t\t\tEveil du L\u00e9man: don't miss the last two outings of the season (11 and 14 August)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/08\/05\/eveil-du-leman-ne-manquez-pas-les-deux-dernieres-sorties-de-la-saison-11-et-14-aout\/\" aria-label=\"Read more about Eveil du L\u00e9man: don&#039;t miss the last two outings of the season (11 and 14 August)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20676 post type-post status-publish format-standard has-post-thumbnail hentry category-renouees\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/08\/05\/appel-a-benevoles-participez-a-nos-actions-darrachage-en-aout\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"665\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Halte-aux-renouees.jpg\" class=\"attachment-full size-full wp-image-20678\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Halte-aux-renouees.jpg 886w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Halte-aux-renouees-300x225.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Halte-aux-renouees-768x576.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/07\/Halte-aux-renouees-16x12.jpg 16w\" sizes=\"(max-width: 886px) 100vw, 886px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Knotweed<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/08\/05\/appel-a-benevoles-participez-a-nos-actions-darrachage-en-aout\/\" >\n\t\t\t\tCall for volunteers: take part in our grubbing-up operations in August!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/08\/05\/appel-a-benevoles-participez-a-nos-actions-darrachage-en-aout\/\" aria-label=\"Read more about Call for volunteers: take part in our grubbing-up operations in August!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20613 post type-post status-publish format-standard has-post-thumbnail hentry category-asl\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/06\/30\/hommage-a-jean-bernard-lachavanne-decede-le-21-juin-2025\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1443\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-scaled.jpg\" class=\"attachment-full size-full wp-image-20617\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-300x169.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-1024x577.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-768x433.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-1536x866.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-2048x1154.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2026\/06\/Jean-Bernard-lachavanne-18x10.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">ASL<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/06\/30\/hommage-a-jean-bernard-lachavanne-decede-le-21-juin-2025\/\" >\n\t\t\t\tTribute to Jean-Bernard Lachavanne, who died on 21 June 2025\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/06\/30\/hommage-a-jean-bernard-lachavanne-decede-le-21-juin-2025\/\" aria-label=\"Read more about Tribute to Jean-Bernard Lachavanne, who died on 21 June 2025\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 June 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20571 post type-post status-publish format-standard has-post-thumbnail hentry category-lemaniques\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/lemaniques-no-135-les-grands-lacs-malades-malgre-eux\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"1306\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Lem135.png\" class=\"attachment-full size-full wp-image-20549\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Lem135.png 921w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Lem135-212x300.png 212w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Lem135-722x1024.png 722w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Lem135-768x1089.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Lem135-8x12.png 8w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Lake Geneva region<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/lemaniques-no-135-les-grands-lacs-malades-malgre-eux\/\" >\n\t\t\t\tL\u00e9maniques no. 135 - The Great Lakes, sick in spite of themselves\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/lemaniques-no-135-les-grands-lacs-malades-malgre-eux\/\" aria-label=\"Read more about L\u00e9maniques no. 135 - The Great Lakes, sick in spite of themselves\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 June 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20532 post type-post status-publish format-standard has-post-thumbnail hentry category-asl\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/decouvrez-le-rapport-dactivites-2024-de-lasl\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/miniature-site-asl-RA-2024.png\" class=\"attachment-full size-full wp-image-20535\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/miniature-site-asl-RA-2024.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/miniature-site-asl-RA-2024-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/miniature-site-asl-RA-2024-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/miniature-site-asl-RA-2024-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/miniature-site-asl-RA-2024-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/miniature-site-asl-RA-2024-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">ASL<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/decouvrez-le-rapport-dactivites-2024-de-lasl\/\" >\n\t\t\t\tDiscover the ASL 2024 activity report\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/decouvrez-le-rapport-dactivites-2024-de-lasl\/\" aria-label=\"Read more about Discover the ASL&#039;s 2024 activity report\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 June 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20601 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/derniere-animation-a-lespace-leman-avant-la-pause-estivale-mardi-1-juillet-de-18h-a-19h30\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Animation-EL.png\" class=\"attachment-full size-full wp-image-20602\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Animation-EL.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Animation-EL-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Animation-EL-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Animation-EL-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Animation-EL-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/Animation-EL-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/derniere-animation-a-lespace-leman-avant-la-pause-estivale-mardi-1-juillet-de-18h-a-19h30\/\" >\n\t\t\t\tLast event at Espace L\u00e9man before the summer break! - Tuesday 1 July from 6pm to 7.30pm\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/derniere-animation-a-lespace-leman-avant-la-pause-estivale-mardi-1-juillet-de-18h-a-19h30\/\" aria-label=\"Read more about Last event at Espace L\u00e9man before the summer break! - Tuesday 1 July from 6pm to 7.30pm\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 June 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20593 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/eveil-du-leman-le-30-juin-a-bourg-en-lavaux-vd-de-7h30-a-9h30\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/sortie-nature-eveil-du-leman-newsletter.png\" class=\"attachment-full size-full wp-image-20599\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/sortie-nature-eveil-du-leman-newsletter.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/sortie-nature-eveil-du-leman-newsletter-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/sortie-nature-eveil-du-leman-newsletter-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/sortie-nature-eveil-du-leman-newsletter-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/sortie-nature-eveil-du-leman-newsletter-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/sortie-nature-eveil-du-leman-newsletter-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/eveil-du-leman-le-30-juin-a-bourg-en-lavaux-vd-de-7h30-a-9h30\/\" >\n\t\t\t\tEveil du L\u00e9man: 30 June in Bourg-en-Lavaux (VD) from 7.30am to 9.30am\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/06\/25\/eveil-du-leman-le-30-juin-a-bourg-en-lavaux-vd-de-7h30-a-9h30\/\" aria-label=\"Read more about Eveil du L\u00e9man: 30 June in Bourg-en-Lavaux (VD) from 7.30am to 9.30am\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 June 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20505 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/30\/decouvrez-lexposition-ports-et-villages-du-leman-a-la-maison-des-associations-de-thonon-du-lundi-26-mai-au-dimanche-8-juin\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1746\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-scaled.jpg\" class=\"attachment-full size-full wp-image-20508\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-300x205.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-1024x698.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-768x524.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-1536x1048.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-2048x1397.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/06\/flyer-a5-pevdl-horizontal-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/30\/decouvrez-lexposition-ports-et-villages-du-leman-a-la-maison-des-associations-de-thonon-du-lundi-26-mai-au-dimanche-8-juin\/\" >\n\t\t\t\tDiscover the \u201cPorts and villages of Lake Geneva\u201d exhibition at the Maison des Associations in Thonon from Monday 26 May to Sunday 8 June.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/30\/decouvrez-lexposition-ports-et-villages-du-leman-a-la-maison-des-associations-de-thonon-du-lundi-26-mai-au-dimanche-8-juin\/\" aria-label=\"Read more about Discover the \u201cPorts and villages of Lake Geneva\u201d exhibition at the Maison des Associations in Thonon from Monday 26 May to Sunday 8 June\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20489 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/retrouvez-lasl-a-festileman-du-7-au-8-juin-a-evian\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"685\" height=\"514\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/festileman-affiche-Copie.jpg\" class=\"attachment-full size-full wp-image-20497\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/festileman-affiche-Copie.jpg 685w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/festileman-affiche-Copie-300x225.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/festileman-affiche-Copie-16x12.jpg 16w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/retrouvez-lasl-a-festileman-du-7-au-8-juin-a-evian\/\" >\n\t\t\t\tASL at FestiL\u00e9man, 7-8 June in Evian\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/retrouvez-lasl-a-festileman-du-7-au-8-juin-a-evian\/\" aria-label=\"Read more about ASL at FestiL\u00e9man, 7-8 June in Evian\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20486 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/eveil-du-leman-observation-artistique-le-4-juin-7h-a-10h-a-la-lagune-des-eaux-vives-ge\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.28-Visuel-site-ASL-sortie-4-juin-dessin-artistique.png\" class=\"attachment-full size-full wp-image-20492\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.28-Visuel-site-ASL-sortie-4-juin-dessin-artistique.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.28-Visuel-site-ASL-sortie-4-juin-dessin-artistique-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.28-Visuel-site-ASL-sortie-4-juin-dessin-artistique-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.28-Visuel-site-ASL-sortie-4-juin-dessin-artistique-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.28-Visuel-site-ASL-sortie-4-juin-dessin-artistique-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.28-Visuel-site-ASL-sortie-4-juin-dessin-artistique-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/eveil-du-leman-observation-artistique-le-4-juin-7h-a-10h-a-la-lagune-des-eaux-vives-ge\/\" >\n\t\t\t\tEveil du L\u00e9man: artistic observation on 4 June (7am to 10am) at the Eaux-Vives lagoon (GE)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/eveil-du-leman-observation-artistique-le-4-juin-7h-a-10h-a-la-lagune-des-eaux-vives-ge\/\" aria-label=\"Read more about Eveil du L\u00e9man: artistic observation on 4 June (7am to 10am) at the Eaux-Vives lagoon (GE)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20483 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/espace-leman-decouvrez-les-animations-en-juin-et-reservez-vos-places\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1442\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-scaled.jpg\" class=\"attachment-full size-full wp-image-18910\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-300x169.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-1024x577.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-768x433.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-1536x865.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-2048x1153.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2024\/10\/Espace_Leman_30.09-1-18x10.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/espace-leman-decouvrez-les-animations-en-juin-et-reservez-vos-places\/\" >\n\t\t\t\tEspace L\u00e9man: find out what's on in June and book your tickets!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/espace-leman-decouvrez-les-animations-en-juin-et-reservez-vos-places\/\" aria-label=\"Read more about Espace L\u00e9man: find out what&#039;s on in June and book your tickets!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20390 post type-post status-publish format-standard has-post-thumbnail hentry category-evenements\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/45e-assemblee-generale-16-juin-2025-aux-eaux-vives-geneve\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.15-news-site-AG-du-16-juin.png\" class=\"attachment-full size-full wp-image-20416\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.15-news-site-AG-du-16-juin.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.15-news-site-AG-du-16-juin-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.15-news-site-AG-du-16-juin-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.15-news-site-AG-du-16-juin-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.15-news-site-AG-du-16-juin-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/2025.05.15-news-site-AG-du-16-juin-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Events<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/45e-assemblee-generale-16-juin-2025-aux-eaux-vives-geneve\/\" >\n\t\t\t\t45th Annual General Meeting: registration, programme and access - Monday 16 June 2025 at Les Eaux-Vives (Geneva)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/28\/45e-assemblee-generale-16-juin-2025-aux-eaux-vives-geneve\/\" aria-label=\"Read more about 45th General Meeting: registration, programme and access - Monday 16 June 2025 at Les Eaux-Vives (Geneva)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20332 post type-post status-publish format-standard has-post-thumbnail hentry category-renouees\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/27\/appel-a-benevoles-pour-nos-actions-en-juin-inscrivez-vous-des-maintenant\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-juin-2025.png\" class=\"attachment-full size-full wp-image-20337\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-juin-2025.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-juin-2025-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-juin-2025-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-juin-2025-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-juin-2025-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-juin-2025-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Knotweed<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/27\/appel-a-benevoles-pour-nos-actions-en-juin-inscrivez-vous-des-maintenant\/\" >\n\t\t\t\tCall for volunteers for our events in June - sign up now!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/27\/appel-a-benevoles-pour-nos-actions-en-juin-inscrivez-vous-des-maintenant\/\" aria-label=\"Read more about Call for volunteers for our actions in June - sign up now!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t27 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20382 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/25\/camps-dete-2025-offrez-a-votre-enfant-6-jours-daventure-inoubliable-sur-le-leman-a-bord-dune-barque-latine-du-xixe-siecle\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/VF_miniature-site-asl-camps-2025.png\" class=\"attachment-full size-full wp-image-20387\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/VF_miniature-site-asl-camps-2025.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/VF_miniature-site-asl-camps-2025-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/VF_miniature-site-asl-camps-2025-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/VF_miniature-site-asl-camps-2025-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/VF_miniature-site-asl-camps-2025-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/VF_miniature-site-asl-camps-2025-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/25\/camps-dete-2025-offrez-a-votre-enfant-6-jours-daventure-inoubliable-sur-le-leman-a-bord-dune-barque-latine-du-xixe-siecle\/\" >\n\t\t\t\tSummer camps 2025: Treat your child to 6 days of unforgettable adventure on Lake Geneva aboard a 19th-century Latin barque!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/25\/camps-dete-2025-offrez-a-votre-enfant-6-jours-daventure-inoubliable-sur-le-leman-a-bord-dune-barque-latine-du-xixe-siecle\/\" aria-label=\"Read more about Summer camps 2025: Treat your child to 6 days of unforgettable adventure on Lake Geneva aboard a 19th-century Latin boat!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20449 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/22\/les-animations-de-lasl-lors-de-faites-du-nautisme-les-24-et-25-mai-a-thonon-les-bains\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"408\" height=\"272\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Faites-du-nautisme-scaled-408x272-1.jpg\" class=\"attachment-full size-full wp-image-20452\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Faites-du-nautisme-scaled-408x272-1.jpg 408w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Faites-du-nautisme-scaled-408x272-1-300x200.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/Faites-du-nautisme-scaled-408x272-1-18x12.jpg 18w\" sizes=\"(max-width: 408px) 100vw, 408px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/22\/les-animations-de-lasl-lors-de-faites-du-nautisme-les-24-et-25-mai-a-thonon-les-bains\/\" >\n\t\t\t\tASL activities at \u201cFaites du Nautisme\u201d on 24 and 25 May in Thonon-les-Bains\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/22\/les-animations-de-lasl-lors-de-faites-du-nautisme-les-24-et-25-mai-a-thonon-les-bains\/\" aria-label=\"Read more about ASL activities at \u201cFaites du Nautisme\u201d on 24 and 25 May in Thonon-les-Bains\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t22 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20354 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/05\/01\/fete-de-la-nature-decouvrez-nos-evenements-du-21-au-25-mai-et-inscrivez-vous-gratuitement\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/miniature-site-asl-fete-de-la-nature-1.png\" class=\"attachment-full size-full wp-image-20360\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/miniature-site-asl-fete-de-la-nature-1.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/miniature-site-asl-fete-de-la-nature-1-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/miniature-site-asl-fete-de-la-nature-1-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/miniature-site-asl-fete-de-la-nature-1-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/miniature-site-asl-fete-de-la-nature-1-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/05\/miniature-site-asl-fete-de-la-nature-1-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/05\/01\/fete-de-la-nature-decouvrez-nos-evenements-du-21-au-25-mai-et-inscrivez-vous-gratuitement\/\" >\n\t\t\t\tF\u00eate de la nature, find out about our events from 21 to 25 May and register for free!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/05\/01\/fete-de-la-nature-decouvrez-nos-evenements-du-21-au-25-mai-et-inscrivez-vous-gratuitement\/\" aria-label=\"Read more about F\u00eate de la nature, find out about our events from 21 to 25 May and register for free!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 May 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20344 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/30\/espace-leman-decouvrez-les-animations-en-mai-et-reservez-vos-places\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Visuel-animations-EL-mars-2025-pour-site-ASL.png\" class=\"attachment-full size-full wp-image-19926\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Visuel-animations-EL-mars-2025-pour-site-ASL.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Visuel-animations-EL-mars-2025-pour-site-ASL-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Visuel-animations-EL-mars-2025-pour-site-ASL-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Visuel-animations-EL-mars-2025-pour-site-ASL-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Visuel-animations-EL-mars-2025-pour-site-ASL-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Visuel-animations-EL-mars-2025-pour-site-ASL-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/30\/espace-leman-decouvrez-les-animations-en-mai-et-reservez-vos-places\/\" >\n\t\t\t\tEspace L\u00e9man: find out what's on in May and book your tickets!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/30\/espace-leman-decouvrez-les-animations-en-mai-et-reservez-vos-places\/\" aria-label=\"Read more about Espace L\u00e9man: find out what&#039;s on in May and book your tickets!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20321 post type-post status-publish format-standard has-post-thumbnail hentry category-renouees\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/28\/appel-a-benevoles-inscrivez-vous-aux-arrachages-de-renouees-en-mai\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-mai-2025.png\" class=\"attachment-full size-full wp-image-20322\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-mai-2025.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-mai-2025-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-mai-2025-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-mai-2025-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-mai-2025-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/benevoles-renouees-mai-2025-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Knotweed<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/28\/appel-a-benevoles-inscrivez-vous-aux-arrachages-de-renouees-en-mai\/\" >\n\t\t\t\tCall for volunteers for our actions in May - sign up now!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/28\/appel-a-benevoles-inscrivez-vous-aux-arrachages-de-renouees-en-mai\/\" aria-label=\"Read more about Call for volunteers for our actions in May - sign up now!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20301 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/14\/jeu-de-piste-itinerant-les-aventuriers-du-leman-du-22-avril-au-7-mai-2025-a-lespace-leman-geneve\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/visuel-site-asl-jeu-de-piste-22-avril-7-mai.png\" class=\"attachment-full size-full wp-image-20306\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/visuel-site-asl-jeu-de-piste-22-avril-7-mai.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/visuel-site-asl-jeu-de-piste-22-avril-7-mai-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/visuel-site-asl-jeu-de-piste-22-avril-7-mai-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/visuel-site-asl-jeu-de-piste-22-avril-7-mai-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/visuel-site-asl-jeu-de-piste-22-avril-7-mai-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/visuel-site-asl-jeu-de-piste-22-avril-7-mai-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/14\/jeu-de-piste-itinerant-les-aventuriers-du-leman-du-22-avril-au-7-mai-2025-a-lespace-leman-geneve\/\" >\n\t\t\t\tLes aventuriers du L\u00e9man\u201c travelling treasure hunt - From 22 April to 7 May 2025 at Espace L\u00e9man (Geneva)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/14\/jeu-de-piste-itinerant-les-aventuriers-du-leman-du-22-avril-au-7-mai-2025-a-lespace-leman-geneve\/\" aria-label=\"Read more about \u201cLes aventuriers du L\u00e9man\u201d travelling treasure hunt - From 22 April to 7 May 2025 at Espace L\u00e9man (Geneva)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t14 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20210 post type-post status-publish format-standard has-post-thumbnail hentry category-renouees\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/appel-a-benevoles-110-dates-pour-donner-un-coup-de-pouce-a-la-biodiversite\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-site-asl-renouees-appel-saison-2025-1.png\" class=\"attachment-full size-full wp-image-20224\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-site-asl-renouees-appel-saison-2025-1.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-site-asl-renouees-appel-saison-2025-1-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-site-asl-renouees-appel-saison-2025-1-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-site-asl-renouees-appel-saison-2025-1-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-site-asl-renouees-appel-saison-2025-1-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-site-asl-renouees-appel-saison-2025-1-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Knotweed<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/appel-a-benevoles-110-dates-pour-donner-un-coup-de-pouce-a-la-biodiversite\/\" >\n\t\t\t\tCall for volunteers: 110 dates to give biodiversity a helping hand!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/appel-a-benevoles-110-dates-pour-donner-un-coup-de-pouce-a-la-biodiversite\/\" aria-label=\"Read more about Call for volunteers: 110 dates to give biodiversity a helping hand!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20226 post type-post status-publish format-standard has-post-thumbnail hentry category-asl\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/lemanscope-rejoignez-le-projet-et-participez-aux-soirees-de-lancement-de-la-saison-2025\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Appel-a-benevoles-saison-2025-lemanscope.png\" class=\"attachment-full size-full wp-image-20229\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Appel-a-benevoles-saison-2025-lemanscope.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Appel-a-benevoles-saison-2025-lemanscope-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Appel-a-benevoles-saison-2025-lemanscope-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Appel-a-benevoles-saison-2025-lemanscope-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Appel-a-benevoles-saison-2025-lemanscope-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Appel-a-benevoles-saison-2025-lemanscope-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">ASL<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/lemanscope-rejoignez-le-projet-et-participez-aux-soirees-de-lancement-de-la-saison-2025\/\" >\n\t\t\t\tL\u00e9manscope: join the project and take part in the launch evenings for the 2025 season\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/lemanscope-rejoignez-le-projet-et-participez-aux-soirees-de-lancement-de-la-saison-2025\/\" aria-label=\"Read more about L\u00e9manscope: join the project and take part in the launch parties for the 2025 season\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20241 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/eautour-du-leman-inscrivez-vos-enfants-aux-camps-dete-de-lasl-juillet-et-aout-2025\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1640\" height=\"924\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-camps-site-asl-2025.png\" class=\"attachment-full size-full wp-image-20245\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-camps-site-asl-2025.png 1640w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-camps-site-asl-2025-300x169.png 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-camps-site-asl-2025-1024x577.png 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-camps-site-asl-2025-768x433.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-camps-site-asl-2025-1536x865.png 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/miniature-camps-site-asl-2025-18x10.png 18w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/eautour-du-leman-inscrivez-vos-enfants-aux-camps-dete-de-lasl-juillet-et-aout-2025\/\" >\n\t\t\t\tEAU'tour du L\u00e9man: register your children for the ASL summer camps (July and August 2025)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/eautour-du-leman-inscrivez-vos-enfants-aux-camps-dete-de-lasl-juillet-et-aout-2025\/\" aria-label=\"Read more about EAU&#039;tour du L\u00e9man: register your children for the ASL summer camps (July and August 2025)\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20247 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/atelier-gratuit-le-monde-invisible-du-leman-jeudi-24-avril-de-14h30-a-16h-au-moulin-de-carra\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1442\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-scaled.jpg\" class=\"attachment-full size-full wp-image-20250\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-300x169.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-1024x577.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-768x433.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-1536x865.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-2048x1154.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/04\/Atelier-monde-invisible-au-MEG_RS_P1022777-18x10.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/atelier-gratuit-le-monde-invisible-du-leman-jeudi-24-avril-de-14h30-a-16h-au-moulin-de-carra\/\" >\n\t\t\t\tFree workshop \"The invisible world of Lake Geneva\" | Thursday 24 April from 13:00 to 14:20 at the Moulin de Carra\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/10\/atelier-gratuit-le-monde-invisible-du-leman-jeudi-24-avril-de-14h30-a-16h-au-moulin-de-carra\/\" aria-label=\"Read more about Free workshop &quot;The invisible world of Lake Geneva&quot; | Thursday 24 April from 13:00 to 14:20 at the Moulin de Carra\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t10 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20098 post type-post status-publish format-standard has-post-thumbnail hentry category-evenement\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/04\/01\/espace-leman-decouvrez-les-animations-en-avril-et-reservez-vos-places\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-scaled.jpg\" class=\"attachment-full size-full wp-image-19732\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-scaled.jpg 2560w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-300x200.jpg 300w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-1024x683.jpg 1024w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-768x512.jpg 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-1536x1024.jpg 1536w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-2048x1365.jpg 2048w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/01\/Espace_Leman_27.11-5-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Event<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/04\/01\/espace-leman-decouvrez-les-animations-en-avril-et-reservez-vos-places\/\" >\n\t\t\t\tEspace L\u00e9man: find out what's on in April and book your tickets!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/04\/01\/espace-leman-decouvrez-les-animations-en-avril-et-reservez-vos-places\/\" aria-label=\"Read more about Espace L\u00e9man: find out what&#039;s on in April and book your tickets!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t1 April 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20124 post type-post status-publish format-standard has-post-thumbnail hentry category-lemaniques\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/asleman.org\/en\/2025\/03\/28\/lemaniques-no-134-amphibiens-et-reptiles-de-la-regon-lemanique-78-despeces-menacees\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1654\" height=\"2339\" src=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture.png\" class=\"attachment-full size-full wp-image-20125\" alt=\"\" srcset=\"https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture.png 1654w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture-212x300.png 212w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture-724x1024.png 724w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture-768x1086.png 768w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture-1086x1536.png 1086w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture-1448x2048.png 1448w, https:\/\/asleman.org\/wp-content\/uploads\/2025\/03\/Lemaniques134_03_2025_1ere-page-couverture-8x12.png 8w\" sizes=\"(max-width: 1654px) 100vw, 1654px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Lake Geneva region<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/asleman.org\/en\/2025\/03\/28\/lemaniques-no-134-amphibiens-et-reptiles-de-la-regon-lemanique-78-despeces-menacees\/\" >\n\t\t\t\tL\u00e9maniques no. 134 - Amphibians and reptiles of the Lake Geneva region: 78% of threatened species!\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/asleman.org\/en\/2025\/03\/28\/lemaniques-no-134-amphibiens-et-reptiles-de-la-regon-lemanique-78-despeces-menacees\/\" aria-label=\"Read more about L\u00e9maniques no. 134 - Amphibians and reptiles in the Lake Geneva region: 78% of threatened species!\" tabindex=\"-1\" >\n\t\t\tRead more \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28 March 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"4\" data-next-page=\"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">\"Previous<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351\/page\/2\/\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351\/page\/3\/\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351\/page\/4\/\"><span class=\"elementor-screen-only\">Page<\/span>4<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351\/page\/2\/\">Next \"<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>News from the ASL<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"class_list":["post-351","page","type-page","status-publish","hentry"],"acf":[],"ase":null,"_links":{"self":[{"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":19,"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351\/revisions"}],"predecessor-version":[{"id":21743,"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/pages\/351\/revisions\/21743"}],"wp:attachment":[{"href":"https:\/\/asleman.org\/en\/wp-json\/wp\/v2\/media?parent=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}